{"id":16631,"date":"2022-03-23T11:14:22","date_gmt":"2022-03-23T10:14:22","guid":{"rendered":"https:\/\/osatech.ch\/shop\/prodotto\/web-site-as-a-service-stage-0-landing-page"},"modified":"2025-12-10T20:10:32","modified_gmt":"2025-12-10T19:10:32","slug":"web-site-as-a-service-stage-0-landing-page","status":"publish","type":"product","link":"https:\/\/osatech.ch\/shop\/index.php\/prodotto\/web-site-as-a-service-stage-0-landing-page","title":{"rendered":"Web Site as a Service &#8211; Stage 0 &#8211; Landing page"},"content":{"rendered":"<p>Soluzione sviluppo landing page, presentazioni e campagne marketing.<\/p>\n<p>Prezzo annuale, contratto minimo 3 anni. Dal 4 anno solo costo piano hosting.<\/p>\n<p>Moduli inclusi:<br \/>\n&#8211; Pagina singola con 4 sezioni di contenuto<br \/>\n&#8211; Elementor + Elementor Pro in comodato d&#8217;uso<br \/>\n&#8211; Yoast seo Plugin free<br \/>\n&#8211; Cookie banner<\/p>\n<p>Hosting classico per la gestione di portali aziendali professionali che include:<br \/>\n&#8211; Spazio web per sito internet e posta elettronica da 15 GB<br \/>\n&#8211; Traffico mensile incluso 100 GB<br \/>\n&#8211; Caselle email con antispam illimitate<br \/>\n&#8211; Certificato SSL encryp.<br \/>\n&#8211; Servizio di backup giornaliero<br \/>\n&#8211; Servizio assistenza Web con nostra tariffa standard<br \/>\n&#8211; Servizio Antivirus &amp; anti malware<br \/>\n&#8211; Security pack con web application firewall<\/p>\n<p>Assistenza tecnica<br \/>\ndal luned\u00ec al venerd\u00ec dalle 8:30 alle 18:00<\/p>\n<p>&#8211; Assistenza per la partenza del servizio<br \/>\n&#8211; Assistenza posta elettronica<br \/>\n&#8211; Migrazione e assistenza sito<br \/>\n&#8211; Gestione dei puntamenti dns<br \/>\n&#8211; Configurazione accessi<br \/>\n&#8211; Aggiornamenti wordpress core &amp; plugin<\/p>\n<p>Per la durata del contratto, la gestione del sito viene effettuata unicamente da OSA TECH. Eventuali richieste di modifiche dopo la pubblicazione verranno quotate separatamente<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soluzione sviluppo landing page, presentazioni e campagne marketing. Prezzo annuale, contratto minimo 3 anni. Dal 4 anno solo costo piano hosting. Moduli inclusi: &#8211; Pagina singola con 4 sezioni di contenuto &#8211; Elementor + Elementor Pro in comodato d&#8217;uso &#8211; Yoast seo Plugin free &#8211; Cookie banner Hosting classico per la gestione di portali aziendali [&hellip;]<\/p>\n","protected":false},"featured_media":32161,"template":"","meta":[],"product_brand":[],"product_cat":[3844],"product_tag":[],"yst_prominent_words":[1822,173,2130,244,1886,1461,343,339,337],"class_list":{"0":"post-16631","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-hosting","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/osatech.ch\/shop\/index.php\/wp-json\/wp\/v2\/product\/16631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osatech.ch\/shop\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/osatech.ch\/shop\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/osatech.ch\/shop\/index.php\/wp-json\/wp\/v2\/media\/32161"}],"wp:attachment":[{"href":"https:\/\/osatech.ch\/shop\/index.php\/wp-json\/wp\/v2\/media?parent=16631"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/osatech.ch\/shop\/index.php\/wp-json\/wp\/v2\/product_brand?post=16631"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/osatech.ch\/shop\/index.php\/wp-json\/wp\/v2\/product_cat?post=16631"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/osatech.ch\/shop\/index.php\/wp-json\/wp\/v2\/product_tag?post=16631"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/osatech.ch\/shop\/index.php\/wp-json\/wp\/v2\/yst_prominent_words?post=16631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}